{"id":433,"date":"2014-11-05T23:01:20","date_gmt":"2014-11-06T02:01:20","guid":{"rendered":"https:\/\/2014.salvador.wordcamp.org\/?post_type=wcb_sponsor&#038;p=433"},"modified":"2014-11-05T23:01:20","modified_gmt":"2014-11-06T02:01:20","slug":"bamp-creative-group","status":"publish","type":"wcb_sponsor","link":"https:\/\/salvador.wordcamp.org\/2014\/sponsor\/bamp-creative-group\/","title":{"rendered":"BAMP Creative Group"},"content":{"rendered":"<p>A <a href=\"http:\/\/www.bampdm.com.br\" title=\"BAMP\" target=\"_blank\" rel=\"nofollow\">BAMP<\/a> Creative Group e\u0301 a mistura das expertises de design, ilustrac\u0327a\u0303o, diagramac\u0327a\u0303o, publicidade e social media, guiados pelo desejo de desenvolver projetos de comunicac\u0327a\u0303o visual e digital que ultrapassem os objetivos e alcancem as expectativas de todos os envolvidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A BAMP Creative Group e\u0301 a mistura das expertises de design, ilustrac\u0327a\u0303o, diagramac\u0327a\u0303o, publicidade e social media, guiados pelo desejo de desenvolver projetos de comunicac\u0327a\u0303o visual e digital que ultrapassem os objetivos e alcancem as expectativas de todos os envolvidos.<\/p>\n","protected":false},"featured_media":434,"template":"","meta":{"_crdt_document":"","_wcpt_sponsor_website":"http:\/\/www.bampdm.com.br","footnotes":""},"sponsor_level":[161320],"class_list":["post-433","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-apoio"],"jetpack_shortlink":"https:\/\/wp.me\/pheUd1-6Z","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsors\/433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":1,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsors\/433\/revisions"}],"predecessor-version":[{"id":435,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsors\/433\/revisions\/435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/media\/434"}],"wp:attachment":[{"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/media?parent=433"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/sponsor_level?post=433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}