{"id":717,"date":"2014-11-14T12:10:56","date_gmt":"2014-11-14T15:10:56","guid":{"rendered":"https:\/\/2014.salvador.wordcamp.org\/?p=717"},"modified":"2014-11-14T12:15:03","modified_gmt":"2014-11-14T15:15:03","slug":"a-programacao-do-wordcamp-salvador-esta-uma-delicia","status":"publish","type":"post","link":"https:\/\/salvador.wordcamp.org\/2014\/a-programacao-do-wordcamp-salvador-esta-uma-delicia\/","title":{"rendered":"A programa\u00e7\u00e3o do WordCamp Salvador est\u00e1 uma del\u00edcia"},"content":{"rendered":"<p>Fala galera, j\u00e1 viram a <a href=\"https:\/\/2014.salvador.wordcamp.org\/programacao\/\" title=\"Programa\u00e7\u00e3o\">programa\u00e7\u00e3o do WordCamp Salvador<\/a>? Diz a verdade, est\u00e1 ou n\u00e3o uma delicia? Tem palestrante vindo l\u00e1 do Amazonas para se apresentar e participar da edi\u00e7\u00e3o Salvador do melhor evento voltado para a comunidade WordPress e voc\u00ea ai &#8220;dando mole&#8221;, deixando para se inscrever no \u00faltimo momento e correndo o risco de ficar sem participar dessa grande festa, &#8220;t\u00e1 vacilando viu&#8221;.<\/p>\n<p>A programa\u00e7\u00e3o conta com palestras voltadas para design, programa\u00e7\u00e3o e conte\u00fado, como teremos duas salas com apresenta\u00e7\u00f5es simult\u00e2neas n\u00f3s tivemos  o cuidado de separar bem os temas para que voc\u00ea possa montar seu roteiro e n\u00e3o ter que escolher entre duas palestras do seu interesse. Vai l\u00e1 e j\u00e1 vai fazendo seu planejamento para n\u00e3o ficar indeciso na hora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fala galera, j\u00e1 viram a programa\u00e7\u00e3o do WordCamp Salvador? Diz a verdade, est\u00e1 ou n\u00e3o uma delicia? Tem palestrante vindo l\u00e1 do Amazonas para se apresentar e participar da edi\u00e7\u00e3o Salvador do melhor evento voltado para a comunidade WordPress e voc\u00ea ai &#8220;dando mole&#8221;, deixando para se inscrever no \u00faltimo momento e correndo o risco &hellip; <a href=\"https:\/\/salvador.wordcamp.org\/2014\/a-programacao-do-wordcamp-salvador-esta-uma-delicia\/\" class=\"more-link\">Continuar a ler<span class=\"screen-reader-text\">A programa\u00e7\u00e3o do WordCamp Salvador est\u00e1 uma del\u00edcia<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1773513,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[324],"tags":[],"class_list":["post-717","post","type-post","status-publish","format-standard","hentry","category-noticias"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pheUd1-bz","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/users\/1773513"}],"replies":[{"embeddable":true,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/comments?post=717"}],"version-history":[{"count":2,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/717\/revisions"}],"predecessor-version":[{"id":719,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/posts\/717\/revisions\/719"}],"wp:attachment":[{"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/media?parent=717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/categories?post=717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salvador.wordcamp.org\/2014\/wp-json\/wp\/v2\/tags?post=717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}